{"id":8811,"date":"2022-09-13T14:56:18","date_gmt":"2022-09-13T14:56:18","guid":{"rendered":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/"},"modified":"2022-09-22T14:19:15","modified_gmt":"2022-09-22T14:19:15","slug":"youtube-news","status":"publish","type":"ona_session","link":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/","title":{"rendered":"Optimizing Your News Experience on YouTube"},"content":{"rendered":"Over the past couple of years, YouTube has worked to raise authoritative voices and reduce the spread of borderline content and harmful misinformation across the platform. Join the news team at YouTube for this session on how to effectively scale a news channel on YouTube. We will share best practices on formats and channel optimization [\u2026] \t\t<div class=\"woocommerce\">\n\t\t\t<div class=\"woocommerce-info wc-memberships-restriction-message wc-memberships-message wc-memberships-content-restricted-message\">\n\t\t\t\tTo access this content, you must purchase <span class=\"wc-memberships-products-grant-access\"><a href=\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/product\/single-registration\/\">ONA21 Single Registration<\/a> or <a href=\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/product\/student-registration\/\">ONA21 Student Registration<\/a><\/span>.\t\t    <\/div>\n\t\t<\/div>\n\t\t","protected":false},"featured_media":0,"template":"","meta":{"start_time":1663851600,"end_time":1663855200,"moderators":[[]],"hashtag":[""],"soundcloud":[""],"scribble":[""],"viafoura":["n"],"youtube":[""],"vimeo":[""],"facebook":[""],"trint":[""],"slideshare":[""],"livestream":[""],"resources":[""],"video_embed":[""],"first_name":"","last_name":"","title":"","organization":"","website":"","twitter":"","_sponsor_url":"","_sponsor_tagline":"","_sponsor_level":""},"tags":[],"event":[53],"class_list":["post-8811","ona_session","type-ona_session","status-publish","hentry","session-type-sponsored","session-room-location-los-feliz","event-ona22","membership-content","access-restricted"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Optimizing Your News Experience on YouTube &#8212; ONA22<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Optimizing Your News Experience on YouTube &#8212; ONA22\" \/>\n<meta property=\"og:description\" content=\"Over the past couple of years, YouTube has worked to raise authoritative voices and reduce the spread of borderline content and harmful misinformation across the platform. Join the news team at YouTube for this session on how to effectively scale a news channel on YouTube. We will share best practices on formats and channel optimization [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/\" \/>\n<meta property=\"og:site_name\" content=\"ONA22\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-22T14:19:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/wp-content\/uploads\/sites\/9\/2022\/05\/cedric-letsch-UZVlSjrIJ3o-unsplash.jpg?resize=1400,787\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"787\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ONAconf\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/\",\"url\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/\",\"name\":\"Optimizing Your News Experience on YouTube &#8212; ONA22\",\"isPartOf\":{\"@id\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/#website\"},\"datePublished\":\"2022-09-13T14:56:18+00:00\",\"dateModified\":\"2022-09-22T14:19:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sessions\",\"item\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Optimizing Your News Experience on YouTube\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/#website\",\"url\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/\",\"name\":\"ONA22\",\"description\":\"Sept. 21\u201324, 2022, in Los Angeles\",\"publisher\":{\"@id\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/#organization\",\"name\":\"Online News Association\",\"url\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/wp-content\/uploads\/sites\/9\/2022\/05\/ONA_blue-1200.png\",\"contentUrl\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/wp-content\/uploads\/sites\/9\/2022\/05\/ONA_blue-1200.png\",\"width\":1200,\"height\":519,\"caption\":\"Online News Association\"},\"image\":{\"@id\":\"https:\/\/journalists-org-develop.go-vip.co\/ona22\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/ONAconf\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Optimizing Your News Experience on YouTube &#8212; ONA22","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/","og_locale":"en_US","og_type":"article","og_title":"Optimizing Your News Experience on YouTube &#8212; ONA22","og_description":"Over the past couple of years, YouTube has worked to raise authoritative voices and reduce the spread of borderline content and harmful misinformation across the platform. Join the news team at YouTube for this session on how to effectively scale a news channel on YouTube. We will share best practices on formats and channel optimization [&hellip;]","og_url":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/","og_site_name":"ONA22","article_modified_time":"2022-09-22T14:19:15+00:00","og_image":[{"width":1400,"height":787,"url":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/wp-content\/uploads\/sites\/9\/2022\/05\/cedric-letsch-UZVlSjrIJ3o-unsplash.jpg?resize=1400,787","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ONAconf","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/","url":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/","name":"Optimizing Your News Experience on YouTube &#8212; ONA22","isPartOf":{"@id":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/#website"},"datePublished":"2022-09-13T14:56:18+00:00","dateModified":"2022-09-22T14:19:15+00:00","breadcrumb":{"@id":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/youtube-news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/"},{"@type":"ListItem","position":2,"name":"Sessions","item":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/sessions\/"},{"@type":"ListItem","position":3,"name":"Optimizing Your News Experience on YouTube"}]},{"@type":"WebSite","@id":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/#website","url":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/","name":"ONA22","description":"Sept. 21\u201324, 2022, in Los Angeles","publisher":{"@id":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/#organization","name":"Online News Association","url":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/#\/schema\/logo\/image\/","url":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/wp-content\/uploads\/sites\/9\/2022\/05\/ONA_blue-1200.png","contentUrl":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/wp-content\/uploads\/sites\/9\/2022\/05\/ONA_blue-1200.png","width":1200,"height":519,"caption":"Online News Association"},"image":{"@id":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/ONAconf"]}]}},"_links":{"self":[{"href":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/wp-json\/wp\/v2\/sessions\/8811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/wp-json\/wp\/v2\/types\/ona_session"}],"wp:attachment":[{"href":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/wp-json\/wp\/v2\/media?parent=8811"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/wp-json\/wp\/v2\/tags?post=8811"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/journalists-org-develop.go-vip.co\/ona22\/wp-json\/wp\/v2\/event?post=8811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}